{"id":2032,"date":"2014-09-05T07:15:56","date_gmt":"2014-09-05T06:15:56","guid":{"rendered":"http:\/\/www.x-iansen.dk\/?p=2032"},"modified":"2021-02-24T14:10:16","modified_gmt":"2021-02-24T13:10:16","slug":"der-buchumschlag","status":"publish","type":"post","link":"https:\/\/www.x-iansen.dk\/index.php\/2014\/09\/05\/der-buchumschlag\/","title":{"rendered":"Der Buchumschlag"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"thumb\" src=\"http:\/\/www.x-iansen.dk\/wp-content\/uploads\/2014\/09\/IMG_0009-92x150.jpg\" align=\"left\" hspace=\"5\"\/>Vor ein paar Tagen schickte Erik Scheriber mir den Buchumschlag zu. In den letzten paar Jahren habe ich viele der Umschl\u00e4ge der vom SFC (<a href=\"http:\/\/www.sciencefiction.dk\" title=\"SFC\" target=\"_blank\">Science Fiction Cirklen<\/a>) herrausgegebenen B\u00fcchern illustriert. Genau so wie ich f\u00fcnf Jahren lang das Temaplakat f\u00fcr den Fantasticon gezeichnet habe.<br \/>\nEs ist die gleiche Illustration wie f\u00fcr meine d\u00e4nische Sammlung.<br \/>\nF\u00fcr mehr \u00fcber meine Illustrationen, siehe <a href=\"https:\/\/www.behance.net\/manfred_x-iansen\" target=\"_blank\">meine Gallerie<\/a><\/p>\n<p>Hier der Umschlag<a href=\"http:\/\/www.x-iansen.dk\/wp-content\/uploads\/2014\/09\/IMG_0010.jpg\"><img decoding=\"async\" class=\"alignnone size-full\" alt=\"IMG_0010.JPG\" src=\"http:\/\/www.x-iansen.dk\/wp-content\/uploads\/2014\/09\/IMG_0010.jpg\" \/><\/a><br \/>\n<em><strong>Der tekst auf der R\u00fcckseite:<\/strong><\/em><\/p>\n<blockquote><p>Kurzgeschichten sind die hohe Kunst der Erz\u00e4hlung. Einen Roman schreiben, mit langen Erkl\u00e4rungen kann jeder. Eine Kurzgeschichte pr\u00e4gnant auf den Punkt bringen, ist hingegen nicht jedemanns<br \/>\nSache. Manfred Christansen\u201a seines Zeichens Autor und Zeichner aus D\u00e4nemark, mehrfach f\u00fcr den Niels Klim Preis vorgeschlagen, zeigt wie es geht. Seine vierzehn spannenden Erz\u00e4hlungen, zum ersten Mal in deutscher Sprache ver\u00f6ffentlicht, kommen schnell zur Sache.<\/p>\n<p>Clever und \u00fcberzeugend. Spannende Science Fiction Geschichten mit<br \/>\nverbl\u00fcffenden Ausgang.<\/p>\n<p>&#8220;Eine Sammlung von gescheiten und sp\u00f6ttischen, bissigen und treffsicheren Kurzgeschichten&#8221; H. A. Miksch<\/p><\/blockquote>\n<p>Nach und nach werde ich Hintergundsmaterial f\u00fcr jede der Geschicten in meinem Blog schreiben und <a href=\"http:\/\/www.x-iansen.dk\/index.php\/category\/galvorst\/\">hier sammeln <\/a><\/p>\n<p> This is a medicine that is only meant to be taken on prescription only. <a href=\"https:\/\/vgrmalaysia.net\/buy-cialis-malaysia.html\">cialis malaysia price<\/a> This makes the supply of these drugs illegal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor ein paar Tagen schickte Erik Scheriber mir den Buchumschlag zu. In den letzten paar Jahren habe ich viele der Umschl\u00e4ge der vom SFC (Science Fiction Cirklen) herrausgegebenen B\u00fcchern illustriert. Genau so wie ich f\u00fcnf Jahren lang das Temaplakat f\u00fcr den Fantasticon gezeichnet habe. Es ist die gleiche Illustration wie f\u00fcr meine d\u00e4nische Sammlung. F\u00fcr [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[104],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6hQ7N-wM","_links":{"self":[{"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/posts\/2032"}],"collection":[{"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/comments?post=2032"}],"version-history":[{"count":8,"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/posts\/2032\/revisions"}],"predecessor-version":[{"id":2807,"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/posts\/2032\/revisions\/2807"}],"wp:attachment":[{"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/media?parent=2032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/categories?post=2032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.x-iansen.dk\/index.php\/wp-json\/wp\/v2\/tags?post=2032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}